{"id":32,"count":6,"description":"","link":"https:\/\/online.salvadoreantours.com\/es\/tag\/mayan-route\/","name":"Mayan Route","slug":"mayan-route","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Mayan Route Archives | Salvadorean Tours | Tour Operador en El Salvador<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/online.salvadoreantours.com\/tag\/mayan-route\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mayan Route Archives | Salvadorean Tours | Tour Operador en El Salvador\" \/>\n<meta property=\"og:url\" content=\"http:\/\/online.salvadoreantours.com\/tag\/mayan-route\/\" \/>\n<meta property=\"og:site_name\" content=\"Salvadorean Tours | Tour Operador en El Salvador\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@salvadoreantour\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"http:\/\/online.salvadoreantours.com\/tag\/mayan-route\/\",\"url\":\"http:\/\/online.salvadoreantours.com\/tag\/mayan-route\/\",\"name\":\"Mayan Route Archives | Salvadorean Tours | Tour Operador en El Salvador\",\"isPartOf\":{\"@id\":\"https:\/\/online.salvadoreantours.com\/#website\"},\"breadcrumb\":{\"@id\":\"http:\/\/online.salvadoreantours.com\/tag\/mayan-route\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/online.salvadoreantours.com\/tag\/mayan-route\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/online.salvadoreantours.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mayan Route\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/online.salvadoreantours.com\/#website\",\"url\":\"https:\/\/online.salvadoreantours.com\/\",\"name\":\"Salvadorean Tours | Tour Operador en El Salvador\",\"description\":\"Los mejores tours, stopovers, experiencias y cosas qu\u00e9 hacer en Salvador\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/online.salvadoreantours.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mayan Route Archives | Salvadorean Tours | Tour Operador en El Salvador","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/online.salvadoreantours.com\/tag\/mayan-route\/","og_locale":"es_ES","og_type":"article","og_title":"Mayan Route Archives | Salvadorean Tours | Tour Operador en El Salvador","og_url":"http:\/\/online.salvadoreantours.com\/tag\/mayan-route\/","og_site_name":"Salvadorean Tours | Tour Operador en El Salvador","twitter_card":"summary_large_image","twitter_site":"@salvadoreantour","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"http:\/\/online.salvadoreantours.com\/tag\/mayan-route\/","url":"http:\/\/online.salvadoreantours.com\/tag\/mayan-route\/","name":"Mayan Route Archives | Salvadorean Tours | Tour Operador en El Salvador","isPartOf":{"@id":"https:\/\/online.salvadoreantours.com\/#website"},"breadcrumb":{"@id":"http:\/\/online.salvadoreantours.com\/tag\/mayan-route\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"http:\/\/online.salvadoreantours.com\/tag\/mayan-route\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/online.salvadoreantours.com\/"},{"@type":"ListItem","position":2,"name":"Mayan Route"}]},{"@type":"WebSite","@id":"https:\/\/online.salvadoreantours.com\/#website","url":"https:\/\/online.salvadoreantours.com\/","name":"Salvadorean Tours | Tour Operador en El Salvador","description":"Los mejores tours, stopovers, experiencias y cosas qu\u00e9 hacer en Salvador","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/online.salvadoreantours.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/online.salvadoreantours.com\/es\/wp-json\/wp\/v2\/tags\/32","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/online.salvadoreantours.com\/es\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/online.salvadoreantours.com\/es\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/online.salvadoreantours.com\/es\/wp-json\/wp\/v2\/posts?tags=32"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}